{"id":981,"date":"2022-06-06T17:59:36","date_gmt":"2022-06-06T21:59:36","guid":{"rendered":"https:\/\/pascalyna.ca\/?post_type=al_product&#038;p=981"},"modified":"2022-06-06T18:51:26","modified_gmt":"2022-06-06T22:51:26","slug":"fda-approved-silicone-set-of-6-stretch-lid","status":"publish","type":"al_product","link":"https:\/\/pascalyna.ca\/fr\/products\/fda-approved-silicone-set-of-6-stretch-lid\/","title":{"rendered":"FDA approved silicone Set of 6  stretch lid"},"content":{"rendered":"<p>Reusable FDA approved silicone FDA approved Set of 6 silicone stretch lid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reusable FDA approved silicone FDA approved Set of 6 silicone stretch lid<\/p>\n","protected":false},"featured_media":895,"template":"","al_product-cat":[86],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FDA approved silicone Set of 6 stretch lid - Pascalyna<\/title>\n<meta name=\"description\" content=\"FDA approved silicone FDA approved Set of 6 silicone stretch lid\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FDA approved silicone Set of 6 stretch lid - Pascalyna\" \/>\n<meta property=\"og:description\" content=\"FDA approved silicone FDA approved Set of 6 silicone stretch lid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/\" \/>\n<meta property=\"og:site_name\" content=\"Pascalyna\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-06T22:51:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pascalyna.ca\/wp-content\/uploads\/2022\/05\/screen-shot-2022-05-27-at-3.58.11-pm-1-edited.png\" \/>\n\t<meta property=\"og:image:width\" content=\"635\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pascalyna.ca\/#website\",\"url\":\"https:\/\/pascalyna.ca\/\",\"name\":\"Pascalyna\",\"description\":\"Popsy&#039;fruit - Cold Pressed Juice \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pascalyna.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#primaryimage\",\"url\":\"https:\/\/pascalyna.ca\/wp-content\/uploads\/2022\/05\/screen-shot-2022-05-27-at-3.58.11-pm-1-edited.png\",\"contentUrl\":\"https:\/\/pascalyna.ca\/wp-content\/uploads\/2022\/05\/screen-shot-2022-05-27-at-3.58.11-pm-1-edited.png\",\"width\":635,\"height\":648,\"caption\":\"Go green and safe with your FDA approved silicone FDA approved Set of stretch lid\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#webpage\",\"url\":\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/\",\"name\":\"FDA approved silicone Set of 6 stretch lid - Pascalyna\",\"isPartOf\":{\"@id\":\"https:\/\/pascalyna.ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#primaryimage\"},\"datePublished\":\"2022-06-06T21:59:36+00:00\",\"dateModified\":\"2022-06-06T22:51:26+00:00\",\"description\":\"FDA approved silicone FDA approved Set of 6 silicone stretch lid\",\"breadcrumb\":{\"@id\":\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pascalyna.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/pascalyna.ca\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FDA approved silicone Set of 6 stretch lid\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FDA approved silicone Set of 6 stretch lid - Pascalyna","description":"FDA approved silicone FDA approved Set of 6 silicone stretch lid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/","og_locale":"fr_FR","og_type":"article","og_title":"FDA approved silicone Set of 6 stretch lid - Pascalyna","og_description":"FDA approved silicone FDA approved Set of 6 silicone stretch lid","og_url":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/","og_site_name":"Pascalyna","article_modified_time":"2022-06-06T22:51:26+00:00","og_image":[{"width":635,"height":648,"url":"https:\/\/pascalyna.ca\/wp-content\/uploads\/2022\/05\/screen-shot-2022-05-27-at-3.58.11-pm-1-edited.png","type":"image\/png"}],"twitter_card":"summary","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/pascalyna.ca\/#website","url":"https:\/\/pascalyna.ca\/","name":"Pascalyna","description":"Popsy&#039;fruit - Cold Pressed Juice ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pascalyna.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#primaryimage","url":"https:\/\/pascalyna.ca\/wp-content\/uploads\/2022\/05\/screen-shot-2022-05-27-at-3.58.11-pm-1-edited.png","contentUrl":"https:\/\/pascalyna.ca\/wp-content\/uploads\/2022\/05\/screen-shot-2022-05-27-at-3.58.11-pm-1-edited.png","width":635,"height":648,"caption":"Go green and safe with your FDA approved silicone FDA approved Set of stretch lid"},{"@type":"WebPage","@id":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#webpage","url":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/","name":"FDA approved silicone Set of 6 stretch lid - Pascalyna","isPartOf":{"@id":"https:\/\/pascalyna.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#primaryimage"},"datePublished":"2022-06-06T21:59:36+00:00","dateModified":"2022-06-06T22:51:26+00:00","description":"FDA approved silicone FDA approved Set of 6 silicone stretch lid","breadcrumb":{"@id":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pascalyna.ca\/products\/fda-approved-silicone-set-of-6-stretch-lid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pascalyna.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/pascalyna.ca\/products\/"},{"@type":"ListItem","position":3,"name":"FDA approved silicone Set of 6 stretch lid"}]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pascalyna.ca\/fr\/wp-json\/wp\/v2\/al_product\/981"}],"collection":[{"href":"https:\/\/pascalyna.ca\/fr\/wp-json\/wp\/v2\/al_product"}],"about":[{"href":"https:\/\/pascalyna.ca\/fr\/wp-json\/wp\/v2\/types\/al_product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pascalyna.ca\/fr\/wp-json\/wp\/v2\/media\/895"}],"wp:attachment":[{"href":"https:\/\/pascalyna.ca\/fr\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"al_product-cat","embeddable":true,"href":"https:\/\/pascalyna.ca\/fr\/wp-json\/wp\/v2\/al_product-cat?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}